{"id":78306,"date":"2024-09-27T14:06:10","date_gmt":"2024-09-27T14:06:10","guid":{"rendered":"https:\/\/mediamaking.com\/?p=78306"},"modified":"2024-09-27T14:06:10","modified_gmt":"2024-09-27T14:06:10","slug":"rental-drone-dji-air-3-fly-more-combo-whit-dji-rc-2","status":"publish","type":"post","link":"https:\/\/mediamaking.com\/en\/rental-drone-dji-air-3-fly-more-combo-whit-dji-rc-2\/","title":{"rendered":"DJI Air 3 Fly More Combo drone whit DJI RC 2"},"content":{"rendered":"<div class=\"subtitolo-noleggio\">DJI Air 3 Fly More Combo drone whit DJI RC 2<\/div>\n<div class=\"text-noleggio\">The DJI Air 3 Fly More Combo drone with DJI RC 2 is an advanced drone designed to deliver exceptional performance for aerial photography enthusiasts and professionals alike. Equipped with a dual camera, one wide-angle and one medium telephoto, this drone allows you to capture 4K images and video with amazing sharpness and a wide dynamic range. Three-axis stabilisation ensures smooth footage even in windy or moving conditions. The DJI Air 3&#8217;s flight system is enhanced by a maximum battery life of 46 minutes, allowing for longer flights and fewer interruptions for recharging.<\/p>\n<p>The DJI RC 2, included in the package, offers precise control with an integrated screen that eliminates the need for a smartphone. With the new O4 video transmission technology, you can enjoy real-time video transmission up to 20 km away, maintaining excellent visual quality even during long-distance flights. <\/p>\n<\/div>\n<div class=\"subtitolo-noleggio\">Specifications<\/div>\n<table class=\"table-noleggio-2-colonne-genrale\">\n<tbody>\n<tr>\n<td class=\"table-colonna-2a-noleggio\">Weight<\/td>\n<td class=\"table-colonna-2b-noleggio\">720 g max.<\/td>\n<\/tr>\n<tr>\n<td class=\"table-colonna-2a-noleggio\">Dimensions<\/td>\n<td class=\"table-colonna-2b-noleggio\">32,6 x 25,8 x 10,6 cm<\/td>\n<\/tr>\n<tr>\n<td class=\"table-colonna-2a-noleggio\">3x medium telephoto lens<\/td>\n<td class=\"table-colonna-2b-noleggio\">Pixel size: 2.4 \u03bcm<br \/>\nEquivalent format: 70 mm<br \/>\nAperture: F 2.8<\/td>\n<\/tr>\n<tr>\n<td class=\"table-colonna-2a-noleggio\">Wide-angle camera<\/td>\n<td class=\"table-colonna-2b-noleggio\">Pixel size: 2.4 \u03bcm<br \/>\nEquivalent format: 24 mm<br \/>\nAperture: F 1.7<\/td>\n<\/tr>\n<tr>\n<td class=\"table-colonna-2a-noleggio\">Camera sensors<\/td>\n<td class=\"table-colonna-2b-noleggio\">CMOS da 1\/1.3\u2033<\/td>\n<\/tr>\n<tr>\n<td class=\"table-colonna-2a-noleggio\">Number of rotors<\/td>\n<td class=\"table-colonna-2b-noleggio\">4 rotors<\/td>\n<\/tr>\n<tr>\n<td class=\"table-colonna-2a-noleggio\">Maximum speed<\/td>\n<td class=\"table-colonna-2b-noleggio\">21 m\/s<\/td>\n<\/tr>\n<tr>\n<td class=\"table-colonna-2a-noleggio\">Maximum operating distance<\/td>\n<td class=\"table-colonna-2b-noleggio\">32000 m<\/td>\n<\/tr>\n<tr>\n<td class=\"table-colonna-2a-noleggio\">Maximum flight height<\/td>\n<td class=\"table-colonna-2b-noleggio\">6000 m<\/td>\n<\/tr>\n<tr>\n<td class=\"table-colonna-2a-noleggio\">Accuracy of horizontal vaulting<\/td>\n<td class=\"table-colonna-2b-noleggio\">0,3 m<\/td>\n<\/tr>\n<tr>\n<td class=\"table-colonna-2a-noleggio\">Accuracy of vertical vaulting<\/td>\n<td class=\"table-colonna-2b-noleggio\">0,1 m<\/td>\n<\/tr>\n<tr>\n<td class=\"table-colonna-2a-noleggio\">Maximum angular pitching speed<\/td>\n<td class=\"table-colonna-2b-noleggio\">35 \u00b0\/s<\/td>\n<\/tr>\n<tr>\n<td class=\"table-colonna-2a-noleggio\">Maximum ascent speed<\/td>\n<td class=\"table-colonna-2b-noleggio\">10 m\/s<\/td>\n<\/tr>\n<tr>\n<td class=\"table-colonna-2a-noleggio\">Maximum descent speed<\/td>\n<td class=\"table-colonna-2b-noleggio\">10 m\/s<\/td>\n<\/tr>\n<tr>\n<td class=\"table-colonna-2a-noleggio\">Operating frequency<\/td>\n<td class=\"table-colonna-2b-noleggio\">2400, 5100, 5800 MHz<\/td>\n<\/tr>\n<tr>\n<td class=\"table-colonna-2a-noleggio\">Video transmission distance<\/td>\n<td class=\"table-colonna-2b-noleggio\">20 km<\/td>\n<\/tr>\n<tr>\n<td class=\"table-colonna-2a-noleggio\">Autonomy<\/td>\n<td class=\"table-colonna-2b-noleggio\">46 min<\/td>\n<\/tr>\n<tr>\n<td class=\"table-colonna-2a-noleggio\">Battery type<\/td>\n<td class=\"table-colonna-2b-noleggio\">Lithium Ion<\/td>\n<\/tr>\n<tr>\n<td class=\"table-colonna-2a-noleggio\">Capacity<\/td>\n<td class=\"table-colonna-2b-noleggio\">4241 mAh\/62,6 Wh<\/td>\n<\/tr>\n<tr>\n<td class=\"table-colonna-2a-noleggio\">Voltage<\/td>\n<td class=\"table-colonna-2b-noleggio\">14,76 V<\/td>\n<\/tr>\n<tr>\n<td class=\"table-colonna-2a-product\">Charging time<\/td>\n<td class=\"table-colonna-2b-product\">80 min<\/td>\n<\/tr>\n<tr>\n<td class=\"table-colonna-2a-noleggio\">Operating temperature<\/td>\n<td class=\"table-colonna-2b-noleggio\">-10 &#8211; 40 \u00b0C<\/td>\n<\/tr>\n<tr>\n<td class=\"table-colonna-2a-noleggio\">AC frequency adapter<\/td>\n<td class=\"table-colonna-2b-noleggio\">50\/60 Hz<\/td>\n<\/tr>\n<tr>\n<td class=\"table-colonna-2a-noleggio\">Color<\/td>\n<td class=\"table-colonna-2b-noleggio\">Black and gray<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>Drone DJI Air 3 Fly More Combo with DJI RC 2 features a dual camera, one wide-angle and one medium telephoto, allowing you to capture images and video in 4K<\/p>\n","protected":false},"author":16,"featured_media":78304,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[811],"tags":[],"class_list":["post-78306","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cameras-dji"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rental DJI Air 3 Fly More Combo drone whit DJI RC 2 - MediaMaking Milan<\/title>\n<meta name=\"description\" content=\"Drone DJI Air 3 Fly More Combo with DJI RC 2 features a dual camera, one wide-angle and one medium telephoto\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mediamaking.com\/en\/rental-drone-dji-air-3-fly-more-combo-whit-dji-rc-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rental DJI Air 3 Fly More Combo drone whit DJI RC 2 - MediaMaking Milan\" \/>\n<meta property=\"og:description\" content=\"Drone DJI Air 3 Fly More Combo with DJI RC 2 features a dual camera, one wide-angle and one medium telephoto\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mediamaking.com\/en\/rental-drone-dji-air-3-fly-more-combo-whit-dji-rc-2\/\" \/>\n<meta property=\"og:site_name\" content=\"MediaMaking\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MediaMaking\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-27T14:06:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mediamaking.com\/assets\/media\/Drone-DJI-Air-3-Fly-More-Combo-con-DJI-RC-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"mmeditor_miriam\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"mmeditor_miriam\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mediamaking.com\\\/en\\\/rental-drone-dji-air-3-fly-more-combo-whit-dji-rc-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mediamaking.com\\\/en\\\/rental-drone-dji-air-3-fly-more-combo-whit-dji-rc-2\\\/\"},\"author\":{\"name\":\"mmeditor_miriam\",\"@id\":\"https:\\\/\\\/mediamaking.com\\\/en\\\/#\\\/schema\\\/person\\\/cfdb0d37489bd4d9e7bfff7847466a74\"},\"headline\":\"DJI Air 3 Fly More Combo drone whit DJI RC 2\",\"datePublished\":\"2024-09-27T14:06:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mediamaking.com\\\/en\\\/rental-drone-dji-air-3-fly-more-combo-whit-dji-rc-2\\\/\"},\"wordCount\":263,\"image\":{\"@id\":\"https:\\\/\\\/mediamaking.com\\\/en\\\/rental-drone-dji-air-3-fly-more-combo-whit-dji-rc-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mediamaking.com\\\/assets\\\/media\\\/Drone-DJI-Air-3-Fly-More-Combo-con-DJI-RC-2.png\",\"articleSection\":[\"DJI\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mediamaking.com\\\/en\\\/rental-drone-dji-air-3-fly-more-combo-whit-dji-rc-2\\\/\",\"url\":\"https:\\\/\\\/mediamaking.com\\\/en\\\/rental-drone-dji-air-3-fly-more-combo-whit-dji-rc-2\\\/\",\"name\":\"Rental DJI Air 3 Fly More Combo drone whit DJI RC 2 - MediaMaking Milan\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mediamaking.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mediamaking.com\\\/en\\\/rental-drone-dji-air-3-fly-more-combo-whit-dji-rc-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mediamaking.com\\\/en\\\/rental-drone-dji-air-3-fly-more-combo-whit-dji-rc-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mediamaking.com\\\/assets\\\/media\\\/Drone-DJI-Air-3-Fly-More-Combo-con-DJI-RC-2.png\",\"datePublished\":\"2024-09-27T14:06:10+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/mediamaking.com\\\/en\\\/#\\\/schema\\\/person\\\/cfdb0d37489bd4d9e7bfff7847466a74\"},\"description\":\"Drone DJI Air 3 Fly More Combo with DJI RC 2 features a dual camera, one wide-angle and one medium telephoto\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mediamaking.com\\\/en\\\/rental-drone-dji-air-3-fly-more-combo-whit-dji-rc-2\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mediamaking.com\\\/en\\\/rental-drone-dji-air-3-fly-more-combo-whit-dji-rc-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/mediamaking.com\\\/en\\\/rental-drone-dji-air-3-fly-more-combo-whit-dji-rc-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mediamaking.com\\\/assets\\\/media\\\/Drone-DJI-Air-3-Fly-More-Combo-con-DJI-RC-2.png\",\"contentUrl\":\"https:\\\/\\\/mediamaking.com\\\/assets\\\/media\\\/Drone-DJI-Air-3-Fly-More-Combo-con-DJI-RC-2.png\",\"width\":1920,\"height\":1080,\"caption\":\"Drone DJI Air 3 Fly More Combo con DJI RC 2\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mediamaking.com\\\/en\\\/rental-drone-dji-air-3-fly-more-combo-whit-dji-rc-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mediamaking.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DJI Air 3 Fly More Combo drone whit DJI RC 2\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mediamaking.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/mediamaking.com\\\/en\\\/\",\"name\":\"MediaMaking\",\"description\":\"Your success is our job!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mediamaking.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mediamaking.com\\\/en\\\/#\\\/schema\\\/person\\\/cfdb0d37489bd4d9e7bfff7847466a74\",\"name\":\"mmeditor_miriam\",\"url\":\"https:\\\/\\\/mediamaking.com\\\/en\\\/author\\\/miriam\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rental DJI Air 3 Fly More Combo drone whit DJI RC 2 - MediaMaking Milan","description":"Drone DJI Air 3 Fly More Combo with DJI RC 2 features a dual camera, one wide-angle and one medium telephoto","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mediamaking.com\/en\/rental-drone-dji-air-3-fly-more-combo-whit-dji-rc-2\/","og_locale":"en_US","og_type":"article","og_title":"Rental DJI Air 3 Fly More Combo drone whit DJI RC 2 - MediaMaking Milan","og_description":"Drone DJI Air 3 Fly More Combo with DJI RC 2 features a dual camera, one wide-angle and one medium telephoto","og_url":"https:\/\/mediamaking.com\/en\/rental-drone-dji-air-3-fly-more-combo-whit-dji-rc-2\/","og_site_name":"MediaMaking","article_publisher":"https:\/\/www.facebook.com\/MediaMaking\/","article_published_time":"2024-09-27T14:06:10+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/mediamaking.com\/assets\/media\/Drone-DJI-Air-3-Fly-More-Combo-con-DJI-RC-2.png","type":"image\/png"}],"author":"mmeditor_miriam","twitter_misc":{"Written by":"mmeditor_miriam","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mediamaking.com\/en\/rental-drone-dji-air-3-fly-more-combo-whit-dji-rc-2\/#article","isPartOf":{"@id":"https:\/\/mediamaking.com\/en\/rental-drone-dji-air-3-fly-more-combo-whit-dji-rc-2\/"},"author":{"name":"mmeditor_miriam","@id":"https:\/\/mediamaking.com\/en\/#\/schema\/person\/cfdb0d37489bd4d9e7bfff7847466a74"},"headline":"DJI Air 3 Fly More Combo drone whit DJI RC 2","datePublished":"2024-09-27T14:06:10+00:00","mainEntityOfPage":{"@id":"https:\/\/mediamaking.com\/en\/rental-drone-dji-air-3-fly-more-combo-whit-dji-rc-2\/"},"wordCount":263,"image":{"@id":"https:\/\/mediamaking.com\/en\/rental-drone-dji-air-3-fly-more-combo-whit-dji-rc-2\/#primaryimage"},"thumbnailUrl":"https:\/\/mediamaking.com\/assets\/media\/Drone-DJI-Air-3-Fly-More-Combo-con-DJI-RC-2.png","articleSection":["DJI"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/mediamaking.com\/en\/rental-drone-dji-air-3-fly-more-combo-whit-dji-rc-2\/","url":"https:\/\/mediamaking.com\/en\/rental-drone-dji-air-3-fly-more-combo-whit-dji-rc-2\/","name":"Rental DJI Air 3 Fly More Combo drone whit DJI RC 2 - MediaMaking Milan","isPartOf":{"@id":"https:\/\/mediamaking.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mediamaking.com\/en\/rental-drone-dji-air-3-fly-more-combo-whit-dji-rc-2\/#primaryimage"},"image":{"@id":"https:\/\/mediamaking.com\/en\/rental-drone-dji-air-3-fly-more-combo-whit-dji-rc-2\/#primaryimage"},"thumbnailUrl":"https:\/\/mediamaking.com\/assets\/media\/Drone-DJI-Air-3-Fly-More-Combo-con-DJI-RC-2.png","datePublished":"2024-09-27T14:06:10+00:00","author":{"@id":"https:\/\/mediamaking.com\/en\/#\/schema\/person\/cfdb0d37489bd4d9e7bfff7847466a74"},"description":"Drone DJI Air 3 Fly More Combo with DJI RC 2 features a dual camera, one wide-angle and one medium telephoto","breadcrumb":{"@id":"https:\/\/mediamaking.com\/en\/rental-drone-dji-air-3-fly-more-combo-whit-dji-rc-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mediamaking.com\/en\/rental-drone-dji-air-3-fly-more-combo-whit-dji-rc-2\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mediamaking.com\/en\/rental-drone-dji-air-3-fly-more-combo-whit-dji-rc-2\/#primaryimage","url":"https:\/\/mediamaking.com\/assets\/media\/Drone-DJI-Air-3-Fly-More-Combo-con-DJI-RC-2.png","contentUrl":"https:\/\/mediamaking.com\/assets\/media\/Drone-DJI-Air-3-Fly-More-Combo-con-DJI-RC-2.png","width":1920,"height":1080,"caption":"Drone DJI Air 3 Fly More Combo con DJI RC 2"},{"@type":"BreadcrumbList","@id":"https:\/\/mediamaking.com\/en\/rental-drone-dji-air-3-fly-more-combo-whit-dji-rc-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mediamaking.com\/en\/"},{"@type":"ListItem","position":2,"name":"DJI Air 3 Fly More Combo drone whit DJI RC 2"}]},{"@type":"WebSite","@id":"https:\/\/mediamaking.com\/en\/#website","url":"https:\/\/mediamaking.com\/en\/","name":"MediaMaking","description":"Your success is our job!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mediamaking.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/mediamaking.com\/en\/#\/schema\/person\/cfdb0d37489bd4d9e7bfff7847466a74","name":"mmeditor_miriam","url":"https:\/\/mediamaking.com\/en\/author\/miriam\/"}]}},"_links":{"self":[{"href":"https:\/\/mediamaking.com\/en\/wp-json\/wp\/v2\/posts\/78306","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mediamaking.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mediamaking.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mediamaking.com\/en\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/mediamaking.com\/en\/wp-json\/wp\/v2\/comments?post=78306"}],"version-history":[{"count":1,"href":"https:\/\/mediamaking.com\/en\/wp-json\/wp\/v2\/posts\/78306\/revisions"}],"predecessor-version":[{"id":78308,"href":"https:\/\/mediamaking.com\/en\/wp-json\/wp\/v2\/posts\/78306\/revisions\/78308"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mediamaking.com\/en\/wp-json\/wp\/v2\/media\/78304"}],"wp:attachment":[{"href":"https:\/\/mediamaking.com\/en\/wp-json\/wp\/v2\/media?parent=78306"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mediamaking.com\/en\/wp-json\/wp\/v2\/categories?post=78306"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mediamaking.com\/en\/wp-json\/wp\/v2\/tags?post=78306"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}